﻿{"id":3572,"date":"2024-04-04T11:44:16","date_gmt":"2024-04-04T09:44:16","guid":{"rendered":"https:\/\/firallibre.com\/new\/organizador\/casa-del-libro\/"},"modified":"2024-04-04T11:44:16","modified_gmt":"2024-04-04T09:44:16","slug":"casa-del-libro","status":"publish","type":"tribe_organizer","link":"https:\/\/firallibre.com\/es\/organizador\/casa-del-libro\/","title":{"rendered":"Casa del Libro"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3572","tribe_organizer","type-tribe_organizer","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa del Libro - Fira Llibre de Val\u00e8ncia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa del Libro - Fira Llibre de Val\u00e8ncia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/firallibre.com\/es\/organizador\/casa-del-libro\/\" \/>\n<meta property=\"og:site_name\" content=\"Fira Llibre de Val\u00e8ncia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fira.Llibre.Valencia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/firallibre.com\/wp-content\/uploads\/2024\/04\/cartel-fira-59.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"913\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@firallibrevlc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/organizador\\\/casa-del-libro\\\/\",\"url\":\"https:\\\/\\\/firallibre.com\\\/es\\\/organizador\\\/casa-del-libro\\\/\",\"name\":\"Casa del Libro - Fira Llibre de Val\u00e8ncia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#website\"},\"datePublished\":\"2024-04-04T09:44:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/organizador\\\/casa-del-libro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/firallibre.com\\\/es\\\/organizador\\\/casa-del-libro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/organizador\\\/casa-del-libro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/firallibre.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa del Libro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/firallibre.com\\\/es\\\/\",\"name\":\"Fira del Llibre de Val\u00e8ncia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/firallibre.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#organization\",\"name\":\"Fira del llibre\",\"url\":\"https:\\\/\\\/firallibre.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/60-fira-llibre-valencia.webp\",\"contentUrl\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/60-fira-llibre-valencia.webp\",\"width\":1890,\"height\":1063,\"caption\":\"Fira del llibre\"},\"image\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fira.Llibre.Valencia\",\"https:\\\/\\\/x.com\\\/firallibrevlc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa del Libro - Fira Llibre de Val\u00e8ncia","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Casa del Libro - Fira Llibre de Val\u00e8ncia","og_url":"https:\/\/firallibre.com\/es\/organizador\/casa-del-libro\/","og_site_name":"Fira Llibre de Val\u00e8ncia","article_publisher":"https:\/\/www.facebook.com\/Fira.Llibre.Valencia","og_image":[{"width":913,"height":1280,"url":"https:\/\/firallibre.com\/wp-content\/uploads\/2024\/04\/cartel-fira-59.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@firallibrevlc","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/firallibre.com\/es\/organizador\/casa-del-libro\/","url":"https:\/\/firallibre.com\/es\/organizador\/casa-del-libro\/","name":"Casa del Libro - Fira Llibre de Val\u00e8ncia","isPartOf":{"@id":"https:\/\/firallibre.com\/es\/#website"},"datePublished":"2024-04-04T09:44:16+00:00","breadcrumb":{"@id":"https:\/\/firallibre.com\/es\/organizador\/casa-del-libro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/firallibre.com\/es\/organizador\/casa-del-libro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/firallibre.com\/es\/organizador\/casa-del-libro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/firallibre.com\/es\/"},{"@type":"ListItem","position":2,"name":"Casa del Libro"}]},{"@type":"WebSite","@id":"https:\/\/firallibre.com\/es\/#website","url":"https:\/\/firallibre.com\/es\/","name":"Fira del Llibre de Val\u00e8ncia","description":"","publisher":{"@id":"https:\/\/firallibre.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/firallibre.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/firallibre.com\/es\/#organization","name":"Fira del llibre","url":"https:\/\/firallibre.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/firallibre.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/firallibre.com\/wp-content\/uploads\/2025\/04\/60-fira-llibre-valencia.webp","contentUrl":"https:\/\/firallibre.com\/wp-content\/uploads\/2025\/04\/60-fira-llibre-valencia.webp","width":1890,"height":1063,"caption":"Fira del llibre"},"image":{"@id":"https:\/\/firallibre.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fira.Llibre.Valencia","https:\/\/x.com\/firallibrevlc"]}]}},"_links":{"self":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_organizer\/3572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_organizer"}],"about":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/types\/tribe_organizer"}],"author":[{"embeddable":true,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_organizer\/3572\/revisions"}],"wp:attachment":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/media?parent=3572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}