﻿{"id":22239,"date":"2026-04-16T10:46:43","date_gmt":"2026-04-16T08:46:43","guid":{"rendered":"https:\/\/firallibre.com\/event\/acte-letno\/"},"modified":"2026-04-21T15:20:59","modified_gmt":"2026-04-21T13:20:59","slug":"del-bancal-al-setrill","status":"publish","type":"tribe_events","link":"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/","title":{"rendered":"Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l&#8217;oli i l&#8217;olivera"},"content":{"rendered":"<p>Del bancal al setrill \u00e9s una obra clau per entendre la cultura de l\u2019olivera i de l\u2019oli al territori valenci\u00e0.Quasi quaranta anys despr\u00e9s del seu primer treball, Roser Cabrera repr\u00e9n la investigaci\u00f3 i amb un nou treball de camp amplia l\u2019\u00e0mbit geogr\u00e0fic, incorpora noves generacions d\u2019informants i analitza la conviv\u00e8ncia entre sistemes tradicionals i moderns, com les alm\u00e0sseres de centrifugaci\u00f3 cont\u00ednua o la producci\u00f3 d\u2019oli ecol\u00f2gic. Amb una mirada etnogr\u00e0fica i ling\u00fc\u00edstica, l\u2019obra fixa un l\u00e8xic tradicional en risc de desaparici\u00f3 i contribueix a preservar un valu\u00f3s patrimoni cultural immaterial valenci\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentaci\u00f3 &#8211; Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l&#8217;oli i l&#8217;olivera \u2013 Roser Cabrera<\/p>\n","protected":false},"author":1,"featured_media":27915,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[70],"class_list":["post-22239","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-presentacio-es","cat_presentacio-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l&#039;oli i l&#039;olivera - Fira Llibre de Val\u00e8ncia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l&#039;oli i l&#039;olivera - Fira Llibre de Val\u00e8ncia\" \/>\n<meta property=\"og:description\" content=\"Presentaci\u00f3 - Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l&#039;oli i l&#039;olivera \u2013 Roser Cabrera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/\" \/>\n<meta property=\"og:site_name\" content=\"Fira Llibre de Val\u00e8ncia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fira.Llibre.Valencia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T13:20:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/firallibre.com\/wp-content\/uploads\/2024\/04\/cartel-fira-59.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"913\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@firallibrevlc\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/del-bancal-al-setrill\\\/\",\"url\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/del-bancal-al-setrill\\\/\",\"name\":\"Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l'oli i l'olivera - Fira Llibre de Val\u00e8ncia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/del-bancal-al-setrill\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/del-bancal-al-setrill\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bancal.jpg\",\"datePublished\":\"2026-04-16T08:46:43+00:00\",\"dateModified\":\"2026-04-21T13:20:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/del-bancal-al-setrill\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/del-bancal-al-setrill\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/del-bancal-al-setrill\\\/#primaryimage\",\"url\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bancal.jpg\",\"contentUrl\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bancal.jpg\",\"width\":540,\"height\":825},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/del-bancal-al-setrill\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/firallibre.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/firallibre.com\\\/es\\\/activitats\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l&#8217;oli i l&#8217;olivera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/firallibre.com\\\/es\\\/\",\"name\":\"Fira del Llibre de Val\u00e8ncia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/firallibre.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#organization\",\"name\":\"Fira del llibre\",\"url\":\"https:\\\/\\\/firallibre.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/60-fira-llibre-valencia.webp\",\"contentUrl\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/60-fira-llibre-valencia.webp\",\"width\":1890,\"height\":1063,\"caption\":\"Fira del llibre\"},\"image\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fira.Llibre.Valencia\",\"https:\\\/\\\/x.com\\\/firallibrevlc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l'oli i l'olivera - Fira Llibre de Val\u00e8ncia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/","og_locale":"es_ES","og_type":"article","og_title":"Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l'oli i l'olivera - Fira Llibre de Val\u00e8ncia","og_description":"Presentaci\u00f3 - Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l'oli i l'olivera \u2013 Roser Cabrera","og_url":"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/","og_site_name":"Fira Llibre de Val\u00e8ncia","article_publisher":"https:\/\/www.facebook.com\/Fira.Llibre.Valencia","article_modified_time":"2026-04-21T13:20:59+00:00","og_image":[{"width":913,"height":1280,"url":"https:\/\/firallibre.com\/wp-content\/uploads\/2024\/04\/cartel-fira-59.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@firallibrevlc","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/","url":"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/","name":"Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l'oli i l'olivera - Fira Llibre de Val\u00e8ncia","isPartOf":{"@id":"https:\/\/firallibre.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/#primaryimage"},"image":{"@id":"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/#primaryimage"},"thumbnailUrl":"https:\/\/firallibre.com\/wp-content\/uploads\/2026\/04\/bancal.jpg","datePublished":"2026-04-16T08:46:43+00:00","dateModified":"2026-04-21T13:20:59+00:00","breadcrumb":{"@id":"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/#primaryimage","url":"https:\/\/firallibre.com\/wp-content\/uploads\/2026\/04\/bancal.jpg","contentUrl":"https:\/\/firallibre.com\/wp-content\/uploads\/2026\/04\/bancal.jpg","width":540,"height":825},{"@type":"BreadcrumbList","@id":"https:\/\/firallibre.com\/es\/event\/del-bancal-al-setrill\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/firallibre.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/firallibre.com\/es\/activitats\/"},{"@type":"ListItem","position":3,"name":"Del bancal al setrill : estudi etnoling\u00fc\u00edstic de l&#8217;oli i l&#8217;olivera"}]},{"@type":"WebSite","@id":"https:\/\/firallibre.com\/es\/#website","url":"https:\/\/firallibre.com\/es\/","name":"Fira del Llibre de Val\u00e8ncia","description":"","publisher":{"@id":"https:\/\/firallibre.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/firallibre.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/firallibre.com\/es\/#organization","name":"Fira del llibre","url":"https:\/\/firallibre.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/firallibre.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/firallibre.com\/wp-content\/uploads\/2025\/04\/60-fira-llibre-valencia.webp","contentUrl":"https:\/\/firallibre.com\/wp-content\/uploads\/2025\/04\/60-fira-llibre-valencia.webp","width":1890,"height":1063,"caption":"Fira del llibre"},"image":{"@id":"https:\/\/firallibre.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fira.Llibre.Valencia","https:\/\/x.com\/firallibrevlc"]}]}},"_links":{"self":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_events\/22239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_events\/22239\/revisions"}],"predecessor-version":[{"id":27917,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_events\/22239\/revisions\/27917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/media\/27915"}],"wp:attachment":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/media?parent=22239"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tags?post=22239"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=22239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}