﻿{"id":22189,"date":"2026-04-16T10:49:15","date_gmt":"2026-04-16T08:49:15","guid":{"rendered":"https:\/\/firallibre.com\/event\/pueblo-blanco-azul\/"},"modified":"2026-05-08T08:29:26","modified_gmt":"2026-05-08T06:29:26","slug":"pueblo-blanco-azul","status":"publish","type":"tribe_events","link":"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/","title":{"rendered":"Pueblo blanco azul"},"content":{"rendered":"<p>Tras una temporada en el extranjero, Elaia regresa al pueblo de sus or\u00edgenes para escribir una novela. Quiere contar la historia de su familia, un entramado de vidas marcadas por la guerra, la dictadura y las dificultades de la vida en el campo andaluz. A medida que los silencios heredados se despejan, emerge una memoria viva, que m\u00e1s que sobre el pasado tiene mucho que decir sobre el presente. Y que llega tambi\u00e9n para sanar una herida: la del duelo sin cerrar por la muerte de su abuela, de la que no pudo despedirse.<\/p>\n<p>Azahara Palomeque escucha las historias que guardan las casas y los olivares, y nos devuelve esas voces ausentes que hablan de amores desafiantes, viajes liberadores, las lealtades y traiciones que rigen un peque\u00f1o mundo. Una novela conmovedora y rupturista en la que lo oral y lo po\u00e9tico se trenzan con cuidado artesano en un canto a las ra\u00edces, a los afectos y a los futuros que a\u00fan es posible imaginar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentaci\u00f3 \u2013 Pueblo blanco azul \u2013 Azahara Palomeque<\/p>\n","protected":false},"author":1,"featured_media":22015,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[80],"tribe_events_cat":[70],"class_list":["post-22189","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-destacados-es","tribe_events_cat-presentacio-es","cat_presentacio-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pueblo blanco azul - Fira Llibre de Val\u00e8ncia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pueblo blanco azul - Fira Llibre de Val\u00e8ncia\" \/>\n<meta property=\"og:description\" content=\"Presentaci\u00f3 \u2013 Pueblo blanco azul \u2013 Azahara Palomeque\" \/>\n<meta property=\"og:url\" content=\"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/\" \/>\n<meta property=\"og:site_name\" content=\"Fira Llibre de Val\u00e8ncia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fira.Llibre.Valencia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T06:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/firallibre.com\/wp-content\/uploads\/2026\/04\/Apalomeque-pueblo-huQQmq.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"992\" \/>\n\t<meta property=\"og:image:height\" content=\"1496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@firallibrevlc\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/pueblo-blanco-azul\\\/\",\"url\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/pueblo-blanco-azul\\\/\",\"name\":\"Pueblo blanco azul - Fira Llibre de Val\u00e8ncia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/pueblo-blanco-azul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/pueblo-blanco-azul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Apalomeque-pueblo-huQQmq.jpg\",\"datePublished\":\"2026-04-16T08:49:15+00:00\",\"dateModified\":\"2026-05-08T06:29:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/pueblo-blanco-azul\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/pueblo-blanco-azul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/pueblo-blanco-azul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Apalomeque-pueblo-huQQmq.jpg\",\"contentUrl\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Apalomeque-pueblo-huQQmq.jpg\",\"width\":992,\"height\":1496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/event\\\/pueblo-blanco-azul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/firallibre.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/firallibre.com\\\/es\\\/activitats\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pueblo blanco azul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/firallibre.com\\\/es\\\/\",\"name\":\"Fira del Llibre de Val\u00e8ncia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/firallibre.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#organization\",\"name\":\"Fira del llibre\",\"url\":\"https:\\\/\\\/firallibre.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/60-fira-llibre-valencia.webp\",\"contentUrl\":\"https:\\\/\\\/firallibre.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/60-fira-llibre-valencia.webp\",\"width\":1890,\"height\":1063,\"caption\":\"Fira del llibre\"},\"image\":{\"@id\":\"https:\\\/\\\/firallibre.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fira.Llibre.Valencia\",\"https:\\\/\\\/x.com\\\/firallibrevlc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pueblo blanco azul - Fira Llibre de Val\u00e8ncia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/","og_locale":"es_ES","og_type":"article","og_title":"Pueblo blanco azul - Fira Llibre de Val\u00e8ncia","og_description":"Presentaci\u00f3 \u2013 Pueblo blanco azul \u2013 Azahara Palomeque","og_url":"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/","og_site_name":"Fira Llibre de Val\u00e8ncia","article_publisher":"https:\/\/www.facebook.com\/Fira.Llibre.Valencia","article_modified_time":"2026-05-08T06:29:26+00:00","og_image":[{"width":992,"height":1496,"url":"https:\/\/firallibre.com\/wp-content\/uploads\/2026\/04\/Apalomeque-pueblo-huQQmq.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@firallibrevlc","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/","url":"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/","name":"Pueblo blanco azul - Fira Llibre de Val\u00e8ncia","isPartOf":{"@id":"https:\/\/firallibre.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/#primaryimage"},"image":{"@id":"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/#primaryimage"},"thumbnailUrl":"https:\/\/firallibre.com\/wp-content\/uploads\/2026\/04\/Apalomeque-pueblo-huQQmq.jpg","datePublished":"2026-04-16T08:49:15+00:00","dateModified":"2026-05-08T06:29:26+00:00","breadcrumb":{"@id":"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/#primaryimage","url":"https:\/\/firallibre.com\/wp-content\/uploads\/2026\/04\/Apalomeque-pueblo-huQQmq.jpg","contentUrl":"https:\/\/firallibre.com\/wp-content\/uploads\/2026\/04\/Apalomeque-pueblo-huQQmq.jpg","width":992,"height":1496},{"@type":"BreadcrumbList","@id":"https:\/\/firallibre.com\/es\/event\/pueblo-blanco-azul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/firallibre.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/firallibre.com\/es\/activitats\/"},{"@type":"ListItem","position":3,"name":"Pueblo blanco azul"}]},{"@type":"WebSite","@id":"https:\/\/firallibre.com\/es\/#website","url":"https:\/\/firallibre.com\/es\/","name":"Fira del Llibre de Val\u00e8ncia","description":"","publisher":{"@id":"https:\/\/firallibre.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/firallibre.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/firallibre.com\/es\/#organization","name":"Fira del llibre","url":"https:\/\/firallibre.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/firallibre.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/firallibre.com\/wp-content\/uploads\/2025\/04\/60-fira-llibre-valencia.webp","contentUrl":"https:\/\/firallibre.com\/wp-content\/uploads\/2025\/04\/60-fira-llibre-valencia.webp","width":1890,"height":1063,"caption":"Fira del llibre"},"image":{"@id":"https:\/\/firallibre.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fira.Llibre.Valencia","https:\/\/x.com\/firallibrevlc"]}]}},"_links":{"self":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_events\/22189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_events\/22189\/revisions"}],"predecessor-version":[{"id":29938,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_events\/22189\/revisions\/29938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/media\/22015"}],"wp:attachment":[{"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/media?parent=22189"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tags?post=22189"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/firallibre.com\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=22189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}